{"id":3,"count":13,"description":"","link":"https:\/\/ellenwhiteaudio.org\/nl\/category\/ellen-g-white\/ellen-g-white-boeken\/","name":"Ellen G. White - Boeken","slug":"ellen-g-white-boeken","taxonomy":"category","parent":2,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ellen G. White - Boeken Archives - Ellen White Audio - Dutch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ellenwhiteaudio.org\/nl\/category\/ellen-g-white\/ellen-g-white-boeken\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ellen G. White - Boeken Archives - Ellen White Audio - Dutch\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ellenwhiteaudio.org\/nl\/category\/ellen-g-white\/ellen-g-white-boeken\/\" \/>\n<meta property=\"og:site_name\" content=\"Ellen White Audio - Dutch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ellenwhiteaudio.org\\\/nl\\\/category\\\/ellen-g-white\\\/ellen-g-white-boeken\\\/\",\"url\":\"https:\\\/\\\/ellenwhiteaudio.org\\\/nl\\\/category\\\/ellen-g-white\\\/ellen-g-white-boeken\\\/\",\"name\":\"Ellen G. White - Boeken Archives - Ellen White Audio - Dutch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ellenwhiteaudio.org\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ellenwhiteaudio.org\\\/nl\\\/category\\\/ellen-g-white\\\/ellen-g-white-boeken\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ellenwhiteaudio.org\\\/nl\\\/category\\\/ellen-g-white\\\/ellen-g-white-boeken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ellenwhiteaudio.org\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ellen G. White\",\"item\":\"https:\\\/\\\/ellenwhiteaudio.org\\\/nl\\\/category\\\/ellen-g-white\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ellen G. White - Boeken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ellenwhiteaudio.org\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/ellenwhiteaudio.org\\\/nl\\\/\",\"name\":\"Ellen White Audio - Dutch\",\"description\":\"Ellen White luisterboeken\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ellenwhiteaudio.org\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ellen G. White - Boeken Archives - Ellen White Audio - Dutch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ellenwhiteaudio.org\/nl\/category\/ellen-g-white\/ellen-g-white-boeken\/","og_locale":"en_US","og_type":"article","og_title":"Ellen G. White - Boeken Archives - Ellen White Audio - Dutch","og_url":"https:\/\/ellenwhiteaudio.org\/nl\/category\/ellen-g-white\/ellen-g-white-boeken\/","og_site_name":"Ellen White Audio - Dutch","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ellenwhiteaudio.org\/nl\/category\/ellen-g-white\/ellen-g-white-boeken\/","url":"https:\/\/ellenwhiteaudio.org\/nl\/category\/ellen-g-white\/ellen-g-white-boeken\/","name":"Ellen G. White - Boeken Archives - Ellen White Audio - Dutch","isPartOf":{"@id":"https:\/\/ellenwhiteaudio.org\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/ellenwhiteaudio.org\/nl\/category\/ellen-g-white\/ellen-g-white-boeken\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ellenwhiteaudio.org\/nl\/category\/ellen-g-white\/ellen-g-white-boeken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ellenwhiteaudio.org\/nl\/"},{"@type":"ListItem","position":2,"name":"Ellen G. White","item":"https:\/\/ellenwhiteaudio.org\/nl\/category\/ellen-g-white\/"},{"@type":"ListItem","position":3,"name":"Ellen G. White - Boeken"}]},{"@type":"WebSite","@id":"https:\/\/ellenwhiteaudio.org\/nl\/#website","url":"https:\/\/ellenwhiteaudio.org\/nl\/","name":"Ellen White Audio - Dutch","description":"Ellen White luisterboeken","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ellenwhiteaudio.org\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/ellenwhiteaudio.org\/nl\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellenwhiteaudio.org\/nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ellenwhiteaudio.org\/nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/ellenwhiteaudio.org\/nl\/wp-json\/wp\/v2\/categories\/2"}],"wp:post_type":[{"href":"https:\/\/ellenwhiteaudio.org\/nl\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}